{"id":376,"date":"2017-01-22T15:52:45","date_gmt":"2017-01-22T15:52:45","guid":{"rendered":"http:\/\/jmcristobal.com.mx\/?p=376"},"modified":"2022-03-27T20:21:52","modified_gmt":"2022-03-28T03:21:52","slug":"enable-ssh-in-cisco-ios-router","status":"publish","type":"post","link":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/","title":{"rendered":"Habilitar SSH en router Cisco IOS"},"content":{"rendered":"<p>Telnet es un protocolo que no utiliza cifrado, donde todo lo que pasa por \u00e9l se muestra en texto plano, por cuestiones de seguridad es recomendable el protocolo SSH (Secure Shell) ya que proporciona una conexi\u00f3n de acceso remoto segura para los dispositivos de red.<\/p>\n\n\n\n<p>La comunicaci\u00f3n entre el cliente y el servidor est\u00e1 cifrada en las versiones 1 y 2 de SSH, la recomendaci\u00f3n es utilizar la versi\u00f3n 2 de este protocolo siempre y cuando el equipo lo permita ya que usa un algoritmo de cifrado con una seguridad mas robusta.<\/p>\n\n\n\n<p>Con los pasos siguientes vamos a configurar el acceso v\u00eda SSH para un router Cisco IOS.<\/p>\n\n\n\n<h4><b><strong>1.- Configurar el usuario para realizar las concexiones al equipos con SSH<\/strong><\/b><\/h4>\n\n\n\n<pre class=\"wp-block-code theme:plain-white height-set:true height:250 width-set:true width:700 toolbar:2 lang:sh decode:true has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\">R1(config)# username &lt;user&gt; privilege 15 password &lt;password&gt;<\/code><\/pre>\n\n\n\n<p>Donde:<br><em><strong>&lt;user><\/strong><\/em> es el nombre que se asignar\u00e1 al usuario para las conexiones remotas por SSH<br><em><strong>&lt;password><\/strong><\/em> aqu\u00ed se especifica la contrase\u00f1a con la que va a iniciar sesi\u00f3n el usuario.<\/p>\n\n\n\n<h4><b><strong>2.- Configurar el nombre de dominio<\/strong><\/b><\/h4>\n\n\n\n<pre class=\"wp-block-code theme:plain-white height-set:true height:250 width-set:true width:700 toolbar:2 lang:sh decode:true has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\">R1(config)#ip domain-name &lt;DomainName&gt;<\/code><\/pre>\n\n\n\n<p>Donde:<br><strong><em>&lt;DomainName><\/em><\/strong> se asigna un nombre de dominio para la conexiones SSH, algo similar a cisco.com o jmcristobal.com.<\/p>\n\n\n\n<h4><b><strong>3.- Generar la llave p\u00fablica o clave para utilizar con SSSH<\/strong><\/b><\/h4>\n\n\n\n<pre class=\"wp-block-code theme:plain-white width:700 lang:sh decode:true has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\">R1(config)#crypto key generate rsa\n\n...\n...\n...\n\nHow many bits in the modulus [512]: &lt;BitsKeyRSA&gt;<\/code><\/pre>\n\n\n\n<p>Donde:<br><strong><em>crypto key generate rsa<\/em><\/strong> indica que vamos a generar un clave con el algoritmo de seguridad RSA (Sistema criptogr\u00e1fico de llave p\u00fablica).<br><strong><em>&lt;BitsKeyRSA><\/em><\/strong> es la logitud en bits de la clave RSA, el valor puede ser de 360 a 2048 bits.<\/p>\n\n\n\n<h4><b><strong>4.- Configurar la version 1 o 2 de SSH<\/strong><\/b><\/h4>\n\n\n\n<pre class=\"wp-block-code theme:plain-white height-set:true height:250 width-set:true width:700 toolbar:2 lang:sh decode:true has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\">R1(config)#ip ssh version &lt;1 or 2&gt;\n<\/code><\/pre>\n\n\n\n<h4><b><strong>5.- Otras configuraciones SSH<\/strong><\/b><\/h4>\n\n\n\n<pre class=\"wp-block-code theme:plain-white height-set:true height:250 width-set:true width:700 toolbar:2 lang:sh decode:true has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\">R1(config)#ip ssh authentication-retries &lt;Number_Attemps&gt;\nR1(config)#ip ssh time-out &lt;Seconds&gt;<\/code><\/pre>\n\n\n\n<p>Donde:<br><strong><em>&lt;Number_Attemps><\/em><\/strong> es el n\u00famero de intentos fallidos o reintentos que tiene el usuario para iniciar sesi\u00f3n en el equipo, si este valor se cumple el inicio de sesi\u00f3n se termina.<br><strong><em>&lt;Seconds><\/em><\/strong> Valor que indica el tiempo de espera en segundos que el dispositivo mantendra activo el inicio de sesi\u00f3n v\u00eda SSH, si este valor se cumple la conexi\u00f3n termina.<\/p>\n\n\n\n<h4><b><strong>6.- Configurar l\u00edneas VTY<\/strong><\/b><\/h4>\n\n\n\n<pre class=\"wp-block-code theme:plain-white height-set:true height:250 width-set:true width:700 toolbar:2 lang:sh decode:true has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\">R1(config)#line vty &lt;VTY range&gt;\nR1(config-line)#transport input ssh\nR1(config-line)#login local<\/code><\/pre>\n\n\n\n<p>Donde:<br><strong><em>&lt;VTY range><\/em><\/strong> es el n\u00famero de las l\u00edneas VTY que se van a configurar.<br><strong><em>&#8216;transport input ssh&#8217;<\/em><\/strong> esta l\u00ednea indica que las sesiones VTY ser\u00e1n a trav\u00e9s del protocolo SSH, otros valores que puede aceptar este l\u00edena es telnet o all.<\/p>\n\n\n\n<h4 class=\"has-text-align-center\"><strong>Ejemplo:<\/strong><\/h4>\n\n\n\n<p class=\"has-black-color has-text-color has-background has-small-font-size\" style=\"background-color:#efefef\">R1(config)#username admin privilege 15 password jmcristobal <br>R1(config)#ip domain-name jmcristobal.com <br><br>R1(config)#crypto key generate rsa  <span class=\"has-inline-color has-vivid-cyan-blue-color\">\/\/Generar la clave con el lagoritmo RSA<\/span><br>The name for the keys will be: R1.jmcristobal.com <br>Choose the size of the key modulus in the range of 360 to 2048 for your   <br>  General Purpose Keys. Choosing a key modulus greater than 512 may take   <br>  a few minutes. <br><br>How many bits in the modulus [512]: 1024 <span class=\"has-inline-color has-vivid-cyan-blue-color\"> \/\/Longitud en bits de la clave, puede ser hasta 2048, recomendable 1024. <\/span><br>% Generating 1024 bit RSA keys, keys will be non-exportable&#8230;[OK] <br><br>R1(config)#ip ssh version 2 <br>R1(config)#ip ssh authentication-retries 2  <span class=\"has-inline-color has-vivid-cyan-blue-color\">\/\/ N\u00famero de reintentos fallidos para el inicio de sesi\u00f3n, con el n\u00famero 2 se tendr\u00e1n tres oportunidades para loguearse, al cumplirse este valor se termina la conexi\u00f3n <\/span><br>R1(config)#ip ssh time-out 30  <span class=\"has-inline-color has-vivid-cyan-blue-color\">\/\/Tiempo de espera para el inicio de sesi\u00f3n <\/span><br><br>R1(config)#line vty 0 15 <br>R1(config-line)#transport input ssh <span class=\"has-inline-color has-vivid-cyan-blue-color\">\/\/Indicar a las l\u00edneas VTY que s\u00f3lo se permitira por SSH <\/span><br>R1(config-line)#login local<\/p>\n\n\n\n<p>Para terminar podemos conectarnos a nuestro dispostivo con un cliente para SSH como PuTTY o desde un equipos cisco con la siguiente l\u00ednea por ejemplo:<\/p>\n\n\n\n<pre class=\"wp-block-code theme:plain-white height-set:true height:250 width-set:true width:700 toolbar:2 lang:sh decode:true has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\">ssh -l &lt;user&gt; -v &lt;version-number&gt; &lt;IP_address&gt;<\/code><\/pre>\n\n\n\n<p>Donde:<br><strong><em>&lt;user><\/em><\/strong> corresponde al nombre de usuario configurado<br><strong><em>&lt;version-number><\/em><\/strong> es el n\u00famero de versi\u00f3n del protocolo SSH<br><strong><em>&lt;IP_address><\/em><\/strong> es la direcci\u00f3n IP a la cual vamos a intentar conectarnos<\/p>\n\n\n\n<p>Acceder desde un equipo con IOS:<\/p>\n\n\n\n<pre class=\"wp-block-code theme:plain-white height-set:true height:250 width-set:true width:700 toolbar:2 lang:sh decode:true has-small-font-size\"><code lang=\"adoc\" class=\"language-adoc\">R1# ssh -l admin -v 2 10.1.1.134<\/code><\/pre>","protected":false},"excerpt":{"rendered":"<p>Telnet is a protocol that does not use encryption, where everything that passes through it is displayed in plain text; for security <\/p>","protected":false},"author":2,"featured_media":1392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[233],"tags":[280,295,340,351,407,423,427],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Enable SSH in Cisco IOS router - JMCristobal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enable SSH in Cisco IOS router - JMCristobal\" \/>\n<meta property=\"og:description\" content=\"Telnet is a protocol that does not use encryption, where everything that passes through it is displayed in plain text; for security\" \/>\n<meta property=\"og:url\" content=\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/\" \/>\n<meta property=\"og:site_name\" content=\"JMCristobal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/JMCristobalHomepage\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-22T15:52:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-28T03:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/wp-content\/uploads\/2022\/01\/RS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"206\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"JMCristobal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jmcristobalhome\" \/>\n<meta name=\"twitter:site\" content=\"@jmcristobalhome\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"JMCristobal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/\"},\"author\":{\"name\":\"JMCristobal\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/e7cca8371cd491cf444cc824f30ae118\"},\"headline\":\"Enable SSH in Cisco IOS router\",\"datePublished\":\"2017-01-22T15:52:45+00:00\",\"dateModified\":\"2022-03-28T03:21:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/\"},\"wordCount\":548,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization\"},\"keywords\":[\"cisco\",\"crypto\",\"ios\",\"key\",\"router\",\"ssh\",\"switch\"],\"articleSection\":[\"Enterprise Infrastructure\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/\",\"url\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/\",\"name\":\"Enable SSH in Cisco IOS router - JMCristobal\",\"isPartOf\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#website\"},\"datePublished\":\"2017-01-22T15:52:45+00:00\",\"dateModified\":\"2022-03-28T03:21:52+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enable SSH in Cisco IOS router\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#website\",\"url\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/\",\"name\":\"JMCristobal\",\"description\":\"Networking and more\",\"publisher\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization\",\"name\":\"JMCristobal\",\"url\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jmcristobal.com\/wp-content\/uploads\/2021\/09\/Logo-JMCristobal.png\",\"contentUrl\":\"https:\/\/jmcristobal.com\/wp-content\/uploads\/2021\/09\/Logo-JMCristobal.png\",\"width\":518,\"height\":436,\"caption\":\"JMCristobal\"},\"image\":{\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.youtube.com\/JMCristobalHomepage\",\"https:\/\/web.facebook.com\/JMCristobalHomepage\",\"https:\/\/twitter.com\/jmcristobalhome\"]},{\"@type\":\"Person\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/e7cca8371cd491cf444cc824f30ae118\",\"name\":\"JMCristobal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/b549739a2a57394801aef27a76efdb3d?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/b549739a2a57394801aef27a76efdb3d?s=96&d=mm&r=g\",\"caption\":\"JMCristobal\"},\"url\":\"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/author\/jmcristobal\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enable SSH in Cisco IOS router - JMCristobal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/","og_locale":"es_ES","og_type":"article","og_title":"Enable SSH in Cisco IOS router - JMCristobal","og_description":"Telnet is a protocol that does not use encryption, where everything that passes through it is displayed in plain text; for security","og_url":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/","og_site_name":"JMCristobal","article_publisher":"https:\/\/web.facebook.com\/JMCristobalHomepage","article_published_time":"2017-01-22T15:52:45+00:00","article_modified_time":"2022-03-28T03:21:52+00:00","og_image":[{"width":350,"height":206,"url":"https:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/wp-content\/uploads\/2022\/01\/RS.png","type":"image\/png"}],"author":"JMCristobal","twitter_card":"summary_large_image","twitter_creator":"@jmcristobalhome","twitter_site":"@jmcristobalhome","twitter_misc":{"Escrito por":"JMCristobal","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/#article","isPartOf":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/"},"author":{"name":"JMCristobal","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/e7cca8371cd491cf444cc824f30ae118"},"headline":"Enable SSH in Cisco IOS router","datePublished":"2017-01-22T15:52:45+00:00","dateModified":"2022-03-28T03:21:52+00:00","mainEntityOfPage":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/"},"wordCount":548,"commentCount":0,"publisher":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization"},"keywords":["cisco","crypto","ios","key","router","ssh","switch"],"articleSection":["Enterprise Infrastructure"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/","url":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/","name":"Enable SSH in Cisco IOS router - JMCristobal","isPartOf":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#website"},"datePublished":"2017-01-22T15:52:45+00:00","dateModified":"2022-03-28T03:21:52+00:00","breadcrumb":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/2017\/01\/22\/enable-ssh-in-cisco-ios-router\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/"},{"@type":"ListItem","position":2,"name":"Enable SSH in Cisco IOS router"}]},{"@type":"WebSite","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#website","url":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/","name":"JMCristobal","description":"Networking and more","publisher":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#organization","name":"JMCristobal","url":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/jmcristobal.com\/wp-content\/uploads\/2021\/09\/Logo-JMCristobal.png","contentUrl":"https:\/\/jmcristobal.com\/wp-content\/uploads\/2021\/09\/Logo-JMCristobal.png","width":518,"height":436,"caption":"JMCristobal"},"image":{"@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/JMCristobalHomepage","https:\/\/web.facebook.com\/JMCristobalHomepage","https:\/\/twitter.com\/jmcristobalhome"]},{"@type":"Person","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/e7cca8371cd491cf444cc824f30ae118","name":"JMCristobal","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/b549739a2a57394801aef27a76efdb3d?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/b549739a2a57394801aef27a76efdb3d?s=96&d=mm&r=g","caption":"JMCristobal"},"url":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/author\/jmcristobal\/"}]}},"jetpack_featured_media_url":"https:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/wp-content\/uploads\/2022\/01\/RS.png","_links":{"self":[{"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/376"}],"collection":[{"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/comments?post=376"}],"version-history":[{"count":9,"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/376\/revisions"}],"predecessor-version":[{"id":1818,"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/posts\/376\/revisions\/1818"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/media\/1392"}],"wp:attachment":[{"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/media?parent=376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/categories?post=376"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ec2-52-7-70-250.compute-1.amazonaws.com\/es\/wp-json\/wp\/v2\/tags?post=376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}